{"id":675,"date":"2016-01-14T11:43:10","date_gmt":"2016-01-14T10:43:10","guid":{"rendered":"https:\/\/plein-jour.eu\/wordpress\/?p=675"},"modified":"2016-01-14T11:43:10","modified_gmt":"2016-01-14T10:43:10","slug":"un-systeme-patriarcal-a-la-tete-de-lecr","status":"publish","type":"post","link":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/","title":{"rendered":"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l&rsquo;ECR"},"content":{"rendered":"<p><strong>Entre esp\u00e9rance et indignation<\/strong><\/p>\n<p><em>Point de vue f\u00e9ministe sur le Synode sur la famille 2015<\/em><\/p>\n<p>Les journalistes ont soulign\u00e9 le dynamisme avec lequel le pape Fran\u00e7ois a dirig\u00e9 le Synode sur la famille 2015. Il a renouvel\u00e9 la m\u00e9thode synodale et prit soin de susciter des discussions v\u00e9ritables. Il insuffle un renouveau. Et il est contest\u00e9 pour cela.<\/p>\n<p>On a rapport\u00e9 trois \u00e9v\u00e9nements survenus pendant le Synode ayant pu avoir pour but de le d\u00e9stabiliser&nbsp;: une lettre d\u2019un groupe d\u2019\u00e9v\u00eaques plus conservateurs, la circulation de fausses photos indiquant qu\u2019il serait atteint d\u2019un cancer et le coming out d\u2019un pr\u00e9lat. \u00c0 travers ces vents contraires, a-t-on indiqu\u00e9, le pape Fran\u00e7ois a tenu bon et il a maintenu la direction souhait\u00e9e pour le Synode. Il avance l\u2019id\u00e9e d\u2019une pastorale de la mis\u00e9ricorde \u00e0 l\u2019attention des personnes qui ne r\u00e9pondent pas aux normes romaines.<\/p>\n<p>Il faut noter qu\u2019il a r\u00e9it\u00e9r\u00e9 \u00e0 maintes reprises l\u2019imprescriptibilit\u00e9 et le caract\u00e8re inchang\u00e9 des visions du SaintSi\u00e8ge sur \u00ab&nbsp;la&nbsp;\u00bb femme et sur la famille. Rappelons bri\u00e8vement les \u00e9nonc\u00e9s fondamentaux de sa vision de \u00ab&nbsp;la&nbsp;\u00bb femme, qui a des cons\u00e9quences directes sur celle de la famille&nbsp;:<\/p>\n<p>1. La femme est cr\u00e9\u00e9e comme \u00ab&nbsp;l\u2019autre&nbsp;\u00bb de l\u2019homme;<\/p>\n<p>2. L\u2019homme et la femme sont \u00e9gaux en dignit\u00e9 humaine; ils ont des fonctions diff\u00e9rentes et compl\u00e9mentaires;<\/p>\n<p>3. La femme a pour r\u00f4le d\u2019\u00eatre m\u00e8re et \u00e9pouse physique ou spirituelle; sa nature physicopsychologique consiste \u00e0 prendre soin, \u00e0 aider, \u00e0 \u00e9couter, \u00e0 \u00e9duquer\u2026<\/p>\n<p>4. L\u2019homme se r\u00e9alise dans le masculin et le f\u00e9minin, tandis que la femme se r\u00e9alise exclusivement dans le f\u00e9minin&nbsp;: interdiction lui est faite de s\u2019approprier les caract\u00e9ristiques masculines;<\/p>\n<p>5. Le double crit\u00e8re moral de l\u2019acte sexuel est l\u2019union (l\u2019amour dans le mariage indissoluble entre un homme et une femme) et la procr\u00e9ation (interdiction de la contraception non naturelle).<\/p>\n<p>On reconna\u00eet un syst\u00e8me symbolique patriarcal exemplaire et accompli. Il se traduit par une hi\u00e9rarchisation des fonctions des hommes et des femmes dans l\u2019organisation de l\u2019\u00c9glise, qui s\u2019est manifest\u00e9e, au Synode sur la famille d\u2019octobre 2015, notamment par une infime repr\u00e9sentation f\u00e9minine, par le non-droit de vote d\u2019une religieuse alors qu\u2019un religieux y a eu acc\u00e8s et par une non-\u00e9coute d\u2019une parole f\u00e9minine \u00ab\u00a0qui tombait \u00e0 plat\u00a0\u00bb (Lucetta Scaraffia).<\/p>\n<p>Ce Synode provoque des sentiments m\u00eal\u00e9s, oscillant entre esp\u00e9rance et indignation. Appel\u00e9 \u00ab&nbsp;le pape des pauvres&nbsp;\u00bb, Fran\u00e7ois d\u00e9fend la r\u00e9conciliation entre les nations, la justice pour les personnes immigrantes, la conscience \u00e9cologique, la critique du capitalisme, une r\u00e9forme de la curie romaine, toutes choses qui soul\u00e8vent l\u2019enthousiasme. Mais comment peut-on isoler la justice relationnelle entre les femmes et les hommes des autres questions de justice sociale? La reproduction du syst\u00e8me patriarcal romain suscite l\u2019indignation.<\/p>\n<p>Les catholiques ont la responsabilit\u00e9 d\u2019opposer un refus \u00e0 cette injustice. Afin de demeurer fid\u00e8les \u00e0 l\u2019\u00e9vangile de J\u00e9sus Christ, ils et elles ont le devoir de refuser d\u2019incarner le patriarcat dans leur vie et dans les communaut\u00e9s locales eccl\u00e9siales.<br \/>\nCe contenu a \u00e9t\u00e9 publi\u00e9 dans Le synode romain sur la famille et les femmes par Denise Couture. Mettez-le en favori avec son permalien.<\/p>\n<p>Publi\u00e9 le 21 d\u00e9cembre 2015 par Denise Couture<br \/>\nExtrait du Site&nbsp;: femmes-ministeres.org<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>A propos Denise Couture<\/p>\n<p>Denise Couture, Ph D. (th\u00e9ologie), est vice-doyenne et professeure titulaire \u00e0 la facult\u00e9 de th\u00e9ologie et de sciences des religions de l&rsquo;Universit\u00e9 de Montr\u00e9al. Elle est membre de l&rsquo;\u00e9quipe de direction du Centre de th\u00e9ologie et d\u2019\u00e9thique contextuelles qu\u00e9b\u00e9coises [CETECQ] et membre de la collective L\u2019autre Parole. Ses champs d\u2019expertise sont les suivants&nbsp;: th\u00e9ologie f\u00e9ministe, femmes et religions, interreligieux f\u00e9ministe; \u00e9thique th\u00e9ologique chr\u00e9tienne, \u00e9thiques et religions, \u00e9thique et sexualit\u00e9; th\u00e9ologie contextuelle, th\u00e9ologie et altermondialisme.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Entre esp\u00e9rance et indignation Point de vue f\u00e9ministe sur le &hellip; <\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-675","post","type-post","status-publish","format-standard","hentry","category-documents"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l&#039;ECR - PLEIN JOUR - Libres d&#039;aimer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l&#039;ECR - PLEIN JOUR - Libres d&#039;aimer\" \/>\n<meta property=\"og:description\" content=\"Entre esp\u00e9rance et indignation Point de vue f\u00e9ministe sur le &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/\" \/>\n<meta property=\"og:site_name\" content=\"PLEIN JOUR - Libres d&#039;aimer\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-14T10:43:10+00:00\" \/>\n<meta name=\"author\" content=\"Plein Jour\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Plein Jour\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/un-systeme-patriarcal-a-la-tete-de-lecr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/un-systeme-patriarcal-a-la-tete-de-lecr\\\/\"},\"author\":{\"name\":\"Plein Jour\",\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#\\\/schema\\\/person\\\/08786bf6936190834e41dbb642a8ec2d\"},\"headline\":\"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l&rsquo;ECR\",\"datePublished\":\"2016-01-14T10:43:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/un-systeme-patriarcal-a-la-tete-de-lecr\\\/\"},\"wordCount\":692,\"publisher\":{\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#organization\"},\"articleSection\":[\"Documents\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/un-systeme-patriarcal-a-la-tete-de-lecr\\\/\",\"url\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/un-systeme-patriarcal-a-la-tete-de-lecr\\\/\",\"name\":\"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l'ECR - PLEIN JOUR - Libres d&#039;aimer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#website\"},\"datePublished\":\"2016-01-14T10:43:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/un-systeme-patriarcal-a-la-tete-de-lecr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/un-systeme-patriarcal-a-la-tete-de-lecr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/un-systeme-patriarcal-a-la-tete-de-lecr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l&rsquo;ECR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/\",\"name\":\"Association Plein Jour\",\"description\":\"Association de soutien pour les compagnes de Pr\u00eatres - A votre \u00e9coute au 06 84 59 06 01\",\"publisher\":{\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#organization\",\"name\":\"Plein Jour\",\"url\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Logo-coq-Plein-Jour-e1603696172827.png\",\"contentUrl\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Logo-coq-Plein-Jour-e1603696172827.png\",\"width\":500,\"height\":374,\"caption\":\"Plein Jour\"},\"image\":{\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/#\\\/schema\\\/person\\\/08786bf6936190834e41dbb642a8ec2d\",\"name\":\"Plein Jour\",\"url\":\"https:\\\/\\\/plein-jour.eu\\\/wordpress\\\/author\\\/admin_pleinjour_eu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l'ECR - PLEIN JOUR - Libres d&#039;aimer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/","og_locale":"fr_FR","og_type":"article","og_title":"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l'ECR - PLEIN JOUR - Libres d&#039;aimer","og_description":"Entre esp\u00e9rance et indignation Point de vue f\u00e9ministe sur le &hellip;","og_url":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/","og_site_name":"PLEIN JOUR - Libres d&#039;aimer","article_published_time":"2016-01-14T10:43:10+00:00","author":"Plein Jour","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Plein Jour","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/#article","isPartOf":{"@id":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/"},"author":{"name":"Plein Jour","@id":"https:\/\/plein-jour.eu\/wordpress\/#\/schema\/person\/08786bf6936190834e41dbb642a8ec2d"},"headline":"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l&rsquo;ECR","datePublished":"2016-01-14T10:43:10+00:00","mainEntityOfPage":{"@id":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/"},"wordCount":692,"publisher":{"@id":"https:\/\/plein-jour.eu\/wordpress\/#organization"},"articleSection":["Documents"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/","url":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/","name":"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l'ECR - PLEIN JOUR - Libres d&#039;aimer","isPartOf":{"@id":"https:\/\/plein-jour.eu\/wordpress\/#website"},"datePublished":"2016-01-14T10:43:10+00:00","breadcrumb":{"@id":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/plein-jour.eu\/wordpress\/un-systeme-patriarcal-a-la-tete-de-lecr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/plein-jour.eu\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Un syst\u00e8me Patriarcal \u00e0 la t\u00eate de l&rsquo;ECR"}]},{"@type":"WebSite","@id":"https:\/\/plein-jour.eu\/wordpress\/#website","url":"https:\/\/plein-jour.eu\/wordpress\/","name":"Association Plein Jour","description":"Association de soutien pour les compagnes de Pr\u00eatres - A votre \u00e9coute au 06 84 59 06 01","publisher":{"@id":"https:\/\/plein-jour.eu\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plein-jour.eu\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/plein-jour.eu\/wordpress\/#organization","name":"Plein Jour","url":"https:\/\/plein-jour.eu\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/plein-jour.eu\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/plein-jour.eu\/wordpress\/wp-content\/uploads\/2020\/10\/Logo-coq-Plein-Jour-e1603696172827.png","contentUrl":"https:\/\/plein-jour.eu\/wordpress\/wp-content\/uploads\/2020\/10\/Logo-coq-Plein-Jour-e1603696172827.png","width":500,"height":374,"caption":"Plein Jour"},"image":{"@id":"https:\/\/plein-jour.eu\/wordpress\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/plein-jour.eu\/wordpress\/#\/schema\/person\/08786bf6936190834e41dbb642a8ec2d","name":"Plein Jour","url":"https:\/\/plein-jour.eu\/wordpress\/author\/admin_pleinjour_eu\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/posts\/675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/comments?post=675"}],"version-history":[{"count":0,"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/posts\/675\/revisions"}],"wp:attachment":[{"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/media?parent=675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/categories?post=675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plein-jour.eu\/wordpress\/wp-json\/wp\/v2\/tags?post=675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}